{"id":8193,"date":"2025-12-12T18:50:02","date_gmt":"2025-12-12T18:50:02","guid":{"rendered":"https:\/\/nutrkw.com\/?page_id=8193"},"modified":"2025-12-18T11:11:07","modified_gmt":"2025-12-18T11:11:07","slug":"home","status":"publish","type":"page","link":"https:\/\/nutrkw.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;34px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Join Them Now<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"metaslider-id-8376\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-108-0 metaslider metaslider-flex metaslider-8376 ml-slider has-dots-nav ms-theme-default-base\" role=\"region\" aria-label=\"\u0639\u0631\u0636 \u0634\u0631\u0627\u0626\u062d \u062c\u062f\u064a\u062f\" data-height=\"350\" data-width=\"700\">\n    <div id=\"metaslider_container_8376\">\n        <div id=\"metaslider_8376\">\n            <ul aria-live='off' class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-8377 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:46:57\" data-filename=\"Untitled-design-4-700x350.png\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-4-700x350.png\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8377 msDefaultImage\" title=\"Untitled design (4)\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div style=\"text-align:center;\">In 40 days<\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8378 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:46:57\" data-filename=\"Untitled-design-8-700x350.png\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-8-700x350.png\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8378 msDefaultImage\" title=\"Untitled design (8)\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 50 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8379 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:46:57\" data-filename=\"8d6cdebf-ad82-4bce-b763-61fd0cf7ff51-700x350.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/8d6cdebf-ad82-4bce-b763-61fd0cf7ff51-700x350.jpg\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8379 msDefaultImage\" title=\"8d6cdebf-ad82-4bce-b763-61fd0cf7ff51\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\">In 45 days<\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8380 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:47:13\" data-filename=\"Untitled-design-7-700x350.png\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-7-700x350.png\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8380 msDefaultImage\" title=\"Untitled design (7)\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 50 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8381 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:47:13\" data-filename=\"5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd-700x350.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd-700x350.jpg\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8381 msDefaultImage\" title=\"5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 90 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8455 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-15 12:19:56\" data-filename=\"9b52efd0-21bb-46cd-b495-19a2c3521de5-700x350.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/9b52efd0-21bb-46cd-b495-19a2c3521de5-700x350.jpg\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8455 msDefaultImage\" title=\"9b52efd0-21bb-46cd-b495-19a2c3521de5\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 100 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_post_slider more_text=&#8221;\u0627\u0642\u0631\u0621 \u0627\u0644\u0645\u0632\u064a\u062f&#8221; show_meta=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_slider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;#ffffff&#8221; admin_label=&#8221;About Me&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#fafafa&#8221; custom_padding=&#8221;100px|0px|54px|0px|false|false&#8221; top_divider_style=&#8221;curve&#8221; top_divider_height=&#8221;6vw&#8221; top_divider_flip=&#8221;vertical&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.20.2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; module_id=&#8221;col-doctor-1&#8243; module_class=&#8221;col-doctor&#8221; _builder_version=&#8221;4.20.2&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/60b4367c-ab17-4188-9a51-91a0889c3126.jpg&#8221; title_text=&#8221;60b4367c-ab17-4188-9a51-91a0889c3126&#8243; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.20.2&#8243; background_image=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-02.png&#8221; background_size=&#8221;contain&#8221; custom_margin=&#8221;|-70px|||false|false&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|1000px|1000px|1000px|1000px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;60px&#8221; box_shadow_color=&#8221;rgba(1,33,92,0.1)&#8221; animation=&#8221;top&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_social_media_follow disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.20.2&#8243; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|||&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/abdallah.elfiky.7?rdid=hWM8QZrhkhM3E4GI&#038;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F1JnoESLoiX%2F#&#8221; _builder_version=&#8221;4.20.2&#8243; background_color=&#8221;#ffc47c&#8221; custom_margin=&#8221;|12px||&#8221; custom_padding=&#8221;6px|6px|6px|6px|true|true&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;twitter&#8221; url=&#8221;https:\/\/x.com\/Abdallahelfiky1&#8243; _builder_version=&#8221;4.20.2&#8243; background_color=&#8221;#ffc47c&#8221; custom_margin=&#8221;|12px||&#8221; custom_padding=&#8221;6px|6px|6px|6px|true|true&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;youtube&#8221; url=&#8221;https:\/\/www.youtube.com\/@drabdallahelfiky7341&#8243; _builder_version=&#8221;4.20.2&#8243; background_color=&#8221;#ffc47c&#8221; custom_margin=&#8221;|12px||&#8221; custom_padding=&#8221;6px|6px|6px|6px|true|true&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]youtube[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_id=&#8221;col-doctor-2&#8243; module_class=&#8221;col-doctor&#8221; _builder_version=&#8221;4.20.2&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.6em&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#ffc47c&#8221; header_3_font_size=&#8221;18px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;14px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Dr. Abdullah Ahmed Al-Feki<\/h2>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/abdallah-el-fiky-169195285\/?lipi=urn%3Ali%3Apage%3Ad_flagship3_profile_verification_details%3B4eUcjMg2T32SQ%2BXdthxNAw%3D%3D\" id=\"ember265\" class=\"active ember-view pv-verified-info-modal__vieweetitle\" data-ntt-old-href=\"\/in\/abdallah-el-fiky-169195285\/\" data-artdeco-is-focused=\"true\"><\/a><\/p>\n<h3>Clinical Nutrition Consultant<\/h3>\n<p>Holder of certificates from the National Nutrition Institute and Cairo University with 10 years of experience in the field of nutrition in the Gulf countries<br \/>Experience with healthy eating programs in Saudi Arabia and Bahrain through Daily Meals programs in Saudi Arabia<br \/>Healthy Land in Bahrain<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.6em&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#ffc47c&#8221; header_3_font_size=&#8221;18px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;14px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><a href=\"https:\/\/www.linkedin.com\/in\/abdallah-el-fiky-169195285\/?lipi=urn%3Ali%3Apage%3Ad_flagship3_profile_verification_details%3B4eUcjMg2T32SQ%2BXdthxNAw%3D%3D\" class=\"active ember-view pv-verified-info-modal__vieweetitle\" data-ntt-old-href=\"\/in\/abdallah-el-fiky-169195285\/\" data-artdeco-is-focused=\"true\">Dr. Aya Mostafa<\/a><\/h2>\n<p>&nbsp;<\/p>\n<h3>Clinical Nutrition Specialist<\/h3>\n<p>Clinical Nutrition Specialist, holder of certificates from Cairo University and the National Nutrition Institute<br \/>Nutrition Specialist at Daily Meals application in Saudi Arabia<br \/>Healthy Land in Bahrain<br \/>Nutrition Specialist for several fitness gyms<br \/>Five years of experience working in the Gulf countries<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_id=&#8221;col-doctor-3&#8243; module_class=&#8221;col-doctor&#8221; _builder_version=&#8221;4.20.2&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/4f5f9213-333e-4b9c-bdc6-c216a2fd5072.jpg&#8221; title_text=&#8221;4f5f9213-333e-4b9c-bdc6-c216a2fd5072&#8243; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.20.2&#8243; background_image=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-02.png&#8221; background_size=&#8221;contain&#8221; custom_margin=&#8221;|||-50px|false|false&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|1000px|1000px|1000px|1000px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;60px&#8221; box_shadow_color=&#8221;rgba(1,33,92,0.1)&#8221; animation=&#8221;top&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_social_media_follow disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.20.2&#8243; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|||&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/abdallah.elfiky.7?rdid=hWM8QZrhkhM3E4GI&#038;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F1JnoESLoiX%2F#&#8221; _builder_version=&#8221;4.20.2&#8243; background_color=&#8221;#ffc47c&#8221; custom_margin=&#8221;|12px||&#8221; custom_padding=&#8221;6px|6px|6px|6px|true|true&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;twitter&#8221; url=&#8221;https:\/\/x.com\/Abdallahelfiky1&#8243; _builder_version=&#8221;4.20.2&#8243; background_color=&#8221;#ffc47c&#8221; custom_margin=&#8221;|12px||&#8221; custom_padding=&#8221;6px|6px|6px|6px|true|true&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;youtube&#8221; url=&#8221;https:\/\/www.youtube.com\/@drabdallahelfiky7341&#8243; _builder_version=&#8221;4.20.2&#8243; background_color=&#8221;#ffc47c&#8221; custom_margin=&#8221;|12px||&#8221; custom_padding=&#8221;6px|6px|6px|6px|true|true&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]youtube[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221;][et_pb_column _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][et_pb_text disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.6em&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#ffc47c&#8221; header_3_font_size=&#8221;18px&#8221; header_3_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;14px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2><a href=\"https:\/\/www.linkedin.com\/in\/abdallah-el-fiky-169195285\/?lipi=urn%3Ali%3Apage%3Ad_flagship3_profile_verification_details%3B4eUcjMg2T32SQ%2BXdthxNAw%3D%3D\" class=\"active ember-view pv-verified-info-modal__vieweetitle\" data-ntt-old-href=\"\/in\/abdallah-el-fiky-169195285\/\" data-artdeco-is-focused=\"true\">Dr. Aya Mostafa<\/a><\/h2>\n<h3>Clinical Nutrition Specialist<\/h3>\n<p>Clinical Nutrition Specialist, holder of certificates from Cairo University and the National Nutrition Institute<br \/>Nutrition Specialist at Daily Meals application in Saudi Arabia<br \/>Healthy Land in Bahrain<br \/>Nutrition Specialist for several fitness gyms<br \/>Five years of experience working in the Gulf countries<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221;][et_pb_column _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][et_pb_text disabled_on=&#8221;off|on|on&#8221; _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Merriweather|700|||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.6em&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_text_color=&#8221;#ffc47c&#8221; header_3_font_size=&#8221;18px&#8221; header_3_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;14px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Dr. Abdullah Ahmed Al-Feki<a href=\"https:\/\/www.linkedin.com\/in\/abdallah-el-fiky-169195285\/?lipi=urn%3Ali%3Apage%3Ad_flagship3_profile_verification_details%3B4eUcjMg2T32SQ%2BXdthxNAw%3D%3D\" id=\"ember265\" class=\"active ember-view pv-verified-info-modal__vieweetitle\" data-ntt-old-href=\"\/in\/abdallah-el-fiky-169195285\/\" data-artdeco-is-focused=\"true\"><\/a><\/h2>\n<h3>Clinical Nutrition Consultant<\/h3>\n<p>Holder of certificates from the National Nutrition Institute and Cairo University with 10 years of experience in the field of nutrition in the Gulf countries<br \/>Experience with healthy eating programs in Saudi Arabia and Bahrain through Daily Meals programs in Saudi Arabia<br \/>Healthy Land in Bahrain<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; next_background_color=&#8221;#f9f9f4&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#34545a&#8221; background_image=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-12.png&#8221; custom_margin=&#8221;||||false&#8221; custom_padding=&#8221;12vw||12vw||true|false&#8221; bottom_divider_style=&#8221;curve&#8221; bottom_divider_height=&#8221;6vw&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_image=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-11.png&#8221; background_size=&#8221;contain&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.20.2&#8243; max_width=&#8221;250px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;Montserrat|500||on|||||&#8221; header_font_size=&#8221;18px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.5em&#8221; header_2_font=&#8221;Merriweather|||on|||||&#8221; header_2_font_size=&#8221;70px&#8221; header_2_letter_spacing=&#8221;5px&#8221; header_2_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;12px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;50px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Personal Nutrition Plan to Transform Your Life<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgzMTgifX0=@&#8221; button_text=&#8221;\u0627\u062d\u062c\u0632 \u0627\u0633\u062a\u0634\u0627\u0631\u062a\u0643 \u0627\u0644\u0622\u0646&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.20.2&#8243; _dynamic_attributes=&#8221;button_url&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;13px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#15c39a&#8221; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;100px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Montserrat|500||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_padding=&#8221;16px|30px|16px|30px|true|true&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;20px&#8221; box_shadow_color=&#8221;rgba(21,195,154,0.3)&#8221; button_letter_spacing_hover=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;2px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Call to Action&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#f9f9f4&#8243; max_width=&#8221;1220px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;60px||60px||true|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;0px||0px||true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;|20px|0|20px|false|true&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; box_shadow_style=&#8221;preset7&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;50px&#8221; box_shadow_color=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.20.2&#8243; background_image=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-08.png&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;top_left&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;130px|110px|68px|110px|false|true&#8221; custom_padding_tablet=&#8221;|90px||90px|false|true&#8221; custom_padding_phone=&#8221;|60px||60px||true&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd.jpg&#8221; title_text=&#8221;5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-3.png&#8221; title_text=&#8221;Untitled design (3)&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgzMTgifX0=@&#8221; button_text=&#8221;\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.20.2&#8243; _dynamic_attributes=&#8221;button_url&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;13px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#15c39a&#8221; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;100px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Montserrat|500||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;50px|||&#8221; custom_padding=&#8221;16px|30px|16px|30px|true|true&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;20px&#8221; box_shadow_color=&#8221;rgba(21,195,154,0.3)&#8221; button_letter_spacing_hover=&#8221;2px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;on&#8221; button_letter_spacing__hover=&#8221;2px&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-6.png&#8221; title_text=&#8221;Untitled design (6)&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; bg_img_2=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-18.jpg&#8221; use_background_color_gradient_2=&#8221;on&#8221; background_color_gradient_stops_2=&#8221;rgba(255,255,255,0) 50%|#f7f7f7 100%&#8221; background_color_gradient_start_2=&#8221;rgba(255,255,255,0)&#8221; background_color_gradient_end_2=&#8221;#f7f7f7&#8243; background_color_gradient_start_position_2=&#8221;50%&#8221; background_color_gradient_overlays_image_2=&#8221;on&#8221; padding_top_2=&#8221;0px&#8221; padding_bottom_1=&#8221;6vw&#8221; padding_bottom_2=&#8221;0px&#8221; padding_left_1=&#8221;10%&#8221; padding_top_bottom_link_1=&#8221;false&#8221; padding_top_bottom_link_2=&#8221;true&#8221; padding_left_right_link_1=&#8221;false&#8221; padding_1_tablet=&#8221;|10%||10%||true&#8221; padding_1_phone=&#8221;&#8221; padding_1_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffffff 0%|#f7f7f7 100%&#8221; background_color_gradient_start=&#8221;#ffffff&#8221; background_color_gradient_end=&#8221;#f7f7f7&#8243; inner_width=&#8221;100%&#8221; inner_max_width=&#8221;100%&#8221; custom_padding=&#8221;54px|0px|0||false|false&#8221; bottom_divider_style=&#8221;curve&#8221; bottom_divider_color=&#8221;#ffffff&#8221; bottom_divider_height=&#8221;6vw&#8221; bottom_divider_arrangement=&#8221;above_content&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;30px|0px|0|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutrition-icon-small-7.png&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;80px&#8221; custom_margin=&#8221;||20px|&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;40px&#8221; box_shadow_spread=&#8221;-10px&#8221; box_shadow_color=&#8221;rgba(91,110,115,0.1)&#8221; animation=&#8221;top&#8221; always_center_on_mobile=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_4_font=&#8221;Merriweather|700|||||||&#8221; header_4_line_height=&#8221;1.8em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Weekly Meal Plan<\/h4>\n<p>A weekly updated meal plan that fits your schedule and health.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutrition-icon-small-6.png&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;80px&#8221; custom_margin=&#8221;||20px|&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;40px&#8221; box_shadow_spread=&#8221;-10px&#8221; box_shadow_color=&#8221;rgba(91,110,115,0.1)&#8221; animation=&#8221;top&#8221; always_center_on_mobile=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_4_font=&#8221;Merriweather|700|||||||&#8221; header_4_line_height=&#8221;1.8em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Monthly Follow-up<\/h4>\n<p>Measurements + Plan Adjustments + Progress Reports<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;30px|0px|0|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutrition-icon-small-5-1.png&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.20.2&#8243; max_width=&#8221;80px&#8221; custom_margin=&#8221;||20px|&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;40px&#8221; box_shadow_spread=&#8221;-10px&#8221; box_shadow_color=&#8221;rgba(91,110,115,0.1)&#8221; animation=&#8221;top&#8221; always_center_on_mobile=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_4_font=&#8221;Merriweather|700|||||||&#8221; header_4_line_height=&#8221;1.8em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Special Programs<\/h4>\n<p>For diabetes, obesity, pregnancy, and colon issues.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutrition-icon-small-4.png&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;80px&#8221; custom_margin=&#8221;||20px|&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; border_radii=&#8221;on|100px|100px|100px|100px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;10px&#8221; box_shadow_blur=&#8221;40px&#8221; box_shadow_spread=&#8221;-10px&#8221; box_shadow_color=&#8221;rgba(91,110,115,0.1)&#8221; animation=&#8221;top&#8221; always_center_on_mobile=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_4_font=&#8221;Merriweather|700|||||||&#8221; header_4_line_height=&#8221;1.8em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Weight Loss Plan<\/h4>\n<p>A precise plan based on calorie count and macronutrient distribution.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-09.png&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Feature&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_pricing_tables _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||18px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_pricing_table title=&#8221;\u0627\u0644\u0628\u0627\u0642\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629&#8221; currency=&#8221;$&#8221; sum=&#8221;499&#8243; button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgzMTgifX0=@&#8221; button_text=&#8221;\u0627\u0634\u062a\u0631\u0643 \u0627\u0644\u0627\u0646&#8221; _builder_version=&#8221;4.20.2&#8243; _dynamic_attributes=&#8221;link_option_url,button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;23px&#8221; button_use_icon=&#8221;off&#8221; button_alignment=&#8221;center&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgxOTMifX0=@&#8221; global_colors_info=&#8221;{}&#8221; sticky_transition=&#8221;on&#8221;]<\/p>\n<p>Weekly Meal Plan<br \/>Follow-up every 7 days<br \/>Contact via WhatsApp<br \/>Monthly progress report<br \/>Daily report<\/p>\n<p>[\/et_pb_pricing_table][et_pb_pricing_table title=&#8221;\u0627\u0644\u0628\u0627\u0642\u0629 \u0627\u0644\u0645\u062a\u0643\u0627\u0645\u0644\u0629&#8221; currency=&#8221;$&#8221; sum=&#8221;899&#8243; button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgzMTgifX0=@&#8221; button_text=&#8221;\u0627\u0634\u062a\u0631\u0643 \u0627\u0644\u0627\u0646&#8221; _builder_version=&#8221;4.20.2&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_use_icon=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_transition=&#8221;on&#8221;]<\/p>\n<p>Weekly plan<br \/>Follow-up every 3 days<br \/>Video call twice a month<br \/>Home workout plan<br \/>24\/7 support<\/p>\n<p>[\/et_pb_pricing_table][et_pb_pricing_table title=&#8221;\u0627\u0644\u0628\u0627\u0642\u0629 \u0627\u0644\u0630\u0647\u0628\u064a\u0629&#8221; currency=&#8221;$&#8221; sum=&#8221;1499&#8243; button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgzMTgifX0=@&#8221; button_text=&#8221;\u0627\u0634\u062a\u0631\u0643 \u0627\u0644\u0627\u0646&#8221; _builder_version=&#8221;4.20.2&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; sticky_transition=&#8221;on&#8221;]<\/p>\n<p>Personalized daily plan<br \/>Daily follow-up<br \/>Unlimited calls<br \/>Complete workout plan<br \/>Fat analysis<\/p>\n<p>[\/et_pb_pricing_table][\/et_pb_pricing_tables][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#f9f9f4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_type=&#8221;circular&#8221; background_color_gradient_stops=&#8221;#f9f9f4 80%|#ffffff 100%&#8221; background_color_gradient_start=&#8221;#f9f9f4&#8243; background_color_gradient_start_position=&#8221;80%&#8221; background_color_gradient_end=&#8221;#ffffff&#8221; background_image=&#8221;https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/nutritionist-15.png&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;top_center&#8221; max_width=&#8221;1220px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;60px||60px||true|false&#8221; custom_padding=&#8221;|16%||16%|false|true&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;10%&#8221; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;30px||30px||true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;Merriweather|700|||||||&#8221; header_3_font_size=&#8221;30px&#8221; header_3_line_height=&#8221;1.6em&#8221; header_4_font=&#8221;Merriweather|700|||||||&#8221; header_4_text_color=&#8221;#15c39a&#8221; header_4_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;500px&#8221; module_alignment=&#8221;center&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;16px&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; header_4_font_size_tablet=&#8221;&#8221; header_4_font_size_phone=&#8221;14px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Contact us<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;30px||30px||true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Email Address&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe076;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; image_icon_background_color=&#8221;#f5ba6a&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;16px&#8221; content_max_width=&#8221;300px&#8221; _builder_version=&#8221;4.20.2&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;11px&#8221; header_letter_spacing=&#8221;1px&#8221; header_line_height=&#8221;2em&#8221; body_font_size=&#8221;12px&#8221; image_icon_custom_padding=&#8221;8px|8px|8px|8px|false|false&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_radii_image=&#8221;on|100%|100%|100%|100%&#8221; use_circle=&#8221;on&#8221; circle_color=&#8221;#f5ba6a&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__sticky_enabled=&#8221;#7EBEC5&#8243; image_icon_background_color__sticky=&#8221;#7EBEC5&#8243;]<\/p>\n<p>admin@nutrkw.com<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;\u0627\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe090;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; image_icon_background_color=&#8221;#cc6b59&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;16px&#8221; content_max_width=&#8221;300px&#8221; _builder_version=&#8221;4.20.2&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;11px&#8221; header_letter_spacing=&#8221;1px&#8221; header_line_height=&#8221;2em&#8221; body_font_size=&#8221;12px&#8221; image_icon_custom_padding=&#8221;8px|8px|8px|8px|false|false&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_radii_image=&#8221;on|100%|100%|100%|100%&#8221; use_circle=&#8221;on&#8221; circle_color=&#8221;#cc6b59&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__sticky_enabled=&#8221;#7EBEC5&#8243; image_icon_background_color__sticky=&#8221;#7EBEC5&#8243;]<\/p>\n<p>(252) 235-1522<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Visit Me&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe081;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; image_icon_background_color=&#8221;#15c39a&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;16px&#8221; content_max_width=&#8221;300px&#8221; _builder_version=&#8221;4.16&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;|700||on|||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;11px&#8221; header_letter_spacing=&#8221;1px&#8221; header_line_height=&#8221;2em&#8221; body_font_size=&#8221;12px&#8221; image_icon_custom_padding=&#8221;8px|8px|8px|8px|false|false&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_radii_image=&#8221;on|100%|100%|100%|100%&#8221; use_circle=&#8221;on&#8221; circle_color=&#8221;#15c39a&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__sticky_enabled=&#8221;#7EBEC5&#8243; image_icon_background_color__sticky=&#8221;#7EBEC5&#8243;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Join Them Now<div id=\"metaslider-id-8376\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-108-0 metaslider metaslider-flex metaslider-8376 ml-slider has-dots-nav ms-theme-default-base\" role=\"region\" aria-label=\"\u0639\u0631\u0636 \u0634\u0631\u0627\u0626\u062d \u062c\u062f\u064a\u062f\" data-height=\"350\" data-width=\"700\">\n    <div id=\"metaslider_container_8376\">\n        <div id=\"metaslider_8376\">\n            <ul aria-live='off' class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-8377 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:46:57\" data-filename=\"Untitled-design-4-700x350.png\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-4-700x350.png\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8377 msDefaultImage\" title=\"Untitled design (4)\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div style=\"text-align:center;\">In 40 days<\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8378 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:46:57\" data-filename=\"Untitled-design-8-700x350.png\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-8-700x350.png\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8378 msDefaultImage\" title=\"Untitled design (8)\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 50 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8379 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:46:57\" data-filename=\"8d6cdebf-ad82-4bce-b763-61fd0cf7ff51-700x350.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/8d6cdebf-ad82-4bce-b763-61fd0cf7ff51-700x350.jpg\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8379 msDefaultImage\" title=\"8d6cdebf-ad82-4bce-b763-61fd0cf7ff51\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div style=\"text-align:center;\">In 45 days<\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8380 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:47:13\" data-filename=\"Untitled-design-7-700x350.png\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/Untitled-design-7-700x350.png\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8380 msDefaultImage\" title=\"Untitled design (7)\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 50 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8381 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-14 11:47:13\" data-filename=\"5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd-700x350.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd-700x350.jpg\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8381 msDefaultImage\" title=\"5fb9aa9c-ecb7-47b5-bcf6-88f4c85134cd\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 90 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-8455 ms-image\" aria-roledescription=\"slide\" data-date=\"2025-12-15 12:19:56\" data-filename=\"9b52efd0-21bb-46cd-b495-19a2c3521de5-700x350.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/nutrkw.com\/en\/%d8%aa%d9%88%d8%a7%d8%b5%d9%84-%d9%85%d8%b9%d9%86%d8%a7\/\" target=\"_blank\" aria-label=\"\u0627\u0646\u0636\u0645 \u0627\u0644\u0627\u0646\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nutrkw.com\/wp-content\/uploads\/2025\/12\/9b52efd0-21bb-46cd-b495-19a2c3521de5-700x350.jpg\" height=\"350\" width=\"700\" alt=\"\" class=\"slider-8376 slide-8455 msDefaultImage\" title=\"9b52efd0-21bb-46cd-b495-19a2c3521de5\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><div> <div> <div style=\"text-align:center;\">In 100 days<\/div> <\/div> <\/div><\/div><\/div><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\u062f\u0643\u062a\u0648\u0631 \u0639\u0628\u062f\u0627\u0644\u0644\u0647 \u0627\u062d\u0645\u062f \u0627\u0644\u0641\u0642\u0649 \u0627\u0633\u062a\u0634\u0627\u0631\u0649 \u0627\u0644\u062a\u063a\u0630\u064a\u0629 \u0627\u0644\u0639\u0644\u0627\u062c\u064a\u0629 \u062d\u0627\u0635\u0644 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0627\u062a \u0645\u0646 \u0627\u0644\u0645\u0639\u0647\u062f \u0627\u0644\u0642\u0648\u0645\u0649 \u0644\u0644\u062a\u063a\u0630\u064a\u0629 \u0648 \u062c\u0627\u0645\u0639\u0629 \u0627\u0644\u0642\u0627\u0647\u0631\u0629 \u062e\u0628\u0631\u0629 \u0661\u0660 \u0633\u0646\u0648\u0627\u062a \u0628\u0645\u062c\u0627\u0644 \u0627\u0644\u062a\u063a\u0630\u064a\u0629 \u062f\u0627\u062e\u0644 \u062f\u0648\u0644 \u0627\u0644\u062e\u0644\u064a\u062c\u062e\u0628\u0631\u0629 \u0628\u0628\u0631\u0627\u0645\u062c \u0627\u0644\u0627\u0643\u0644 \u0627\u0644\u0635\u062d\u064a \u062f\u0627\u062e\u0644 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629 \u0648 \u0627\u0644\u0628\u062d\u0631\u064a\u0646 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0628\u0631\u0627\u0645\u062c daily meals \u0628\u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629Healthy land \u0628\u0627\u0644\u0628\u062d\u0631\u064a\u0646\u062f\u0643\u062a\u0648\u0631\u0629 \u0627\u064a\u0647 \u0645\u0635\u0637\u0641\u0649 &nbsp; \u0623\u062e\u0635\u0627\u0626\u064a\u0629 \u062a\u063a\u0630\u064a\u0629 \u0627\u0644\u0639\u0644\u0627\u062c\u064a\u0629 \u0623\u062e\u0635\u0627\u0626\u064a\u0629 \u0627\u0644\u062a\u063a\u0630\u064a\u0629 \u0627\u0644\u0639\u0644\u0627\u062c\u064a\u0629 \u062d\u0627\u0635\u0644\u0629 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0627\u062a [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-8193","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/pages\/8193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/comments?post=8193"}],"version-history":[{"count":41,"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/pages\/8193\/revisions"}],"predecessor-version":[{"id":8484,"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/pages\/8193\/revisions\/8484"}],"wp:attachment":[{"href":"https:\/\/nutrkw.com\/en\/wp-json\/wp\/v2\/media?parent=8193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}